{"id":16223,"date":"2022-11-10T13:33:39","date_gmt":"2022-11-10T12:33:39","guid":{"rendered":"http:\/\/www.crfj.org\/?p=16223"},"modified":"2023-05-31T15:37:01","modified_gmt":"2023-05-31T13:37:01","slug":"nouveau-financement-anr-pour-les-postdoctorants-en-sciences-humaines-et-sociales-access-erc-starting-2023","status":"publish","type":"post","link":"https:\/\/www.crfj.org\/en\/nouveau-financement-anr-pour-les-postdoctorants-en-sciences-humaines-et-sociales-access-erc-starting-2023\/","title":{"rendered":"FINANCEMENT : Appel ANR pour les postdoctorants en SHS : ACCESS ERC Starting 2023."},"content":{"rendered":"<p style=\"text-align: justify;\">Un nouveau programme de financement ANR tout sp\u00e9cialement d\u00e9di\u00e9 aux postdoctorants en sciences humaines et sociales est actuellement disponible, il s\u2019agit de l\u2019ACCESS ERC Starting. Son objectif est d\u2019accompagner de jeunes chercheurs et chercheuses dans la pr\u00e9paration d\u2019une premi\u00e8re candidature \u00e0 l\u2019ERC Starting Grants, en leur permettant notamment de renforcer leur CV, afin qu\u2019ils soient comp\u00e9titifs \u00e0 cet appel.<\/p>\n<p style=\"text-align: justify;\">Il est destin\u00e9 en particulier aux postdoctorants :<\/p>\n<ul style=\"text-align: justify;\">\n<li>ayant r\u00e9cemment soutenu une th\u00e8se,<\/li>\n<li>avec une exp\u00e9rience internationale d\u2019un an minimum,<\/li>\n<li>\u00e9ligibles et int\u00e9ress\u00e9s par une future candidature \u00e0 l\u2019appel \u00e0 projet europ\u00e9en&nbsp;<a href=\"https:\/\/erc.europa.eu\/apply-grant\/starting-grant\">ERC starting grant<\/a>.<\/li>\n<li>Sa <strong>date limite de d\u00e9p\u00f4t<\/strong>&nbsp;est le 5 janvier 2023.<\/li>\n<\/ul>\n<p>Les candidatures des postdoctorants ayant une exp\u00e9rience internationale &#8211; via les UMIFRE notamment &#8211; sont donc les bienvenues.<\/p>\n<div class=\"\"><span class=\"\"><span class=\"\" style=\"color: #555555; font-family: Roboto, Arial, Helvetica, sans-serif;\">Pour plus d\u2019informations, vous pouvez&nbsp;contacter au CRFJ&nbsp;<\/span><\/span><span class=\"\" style=\"color: #555555; font-family: Roboto, Arial, Helvetica, sans-serif;\"><span class=\"\"><a class=\"\" href=\"mailto:marie.fleck@cnrs.fr\">marie.fleck@cnrs.fr<\/a> et <\/span><\/span><span class=\"\"><span class=\"\" style=\"color: #555555; font-family: Roboto, Arial, Helvetica, sans-serif;\">consulter le texte de l\u2019appel \u00e0 projet et toute autre information sur le site de l\u2019ANR&nbsp;:&nbsp;<\/span><\/span><a class=\"\" href=\"https:\/\/anr.fr\/fr\/detail\/call\/appel-a-projets-access-erc-starting-access-erc-edition-2023\/\">https:\/\/anr.fr\/fr\/detail\/call\/appel-a-projets-access-erc-starting-access-erc-edition-2023\/<\/a><\/div>\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Un nouveau programme de financement ANR tout sp\u00e9cialement d\u00e9di\u00e9 aux postdoctorants en sciences humaines et sociales est actuellement disponible, il s\u2019agit de l\u2019ACCESS ERC Starting. Son objectif est d\u2019accompagner de jeunes chercheurs et chercheuses dans la pr\u00e9paration d\u2019une premi\u00e8re candidature \u00e0 l\u2019ERC Starting Grants, en leur permettant notamment de renforcer leur CV, afin qu\u2019ils soient comp\u00e9titifs [&hellip;]<\/p>","protected":false},"author":2,"featured_media":16227,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[151,148,149,150,152],"_links":{"self":[{"href":"https:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/posts\/16223"}],"collection":[{"href":"https:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/comments?post=16223"}],"version-history":[{"count":4,"href":"https:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/posts\/16223\/revisions"}],"predecessor-version":[{"id":16717,"href":"https:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/posts\/16223\/revisions\/16717"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/media\/16227"}],"wp:attachment":[{"href":"https:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/media?parent=16223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/categories?post=16223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/tags?post=16223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}