{"id":15958,"date":"2022-10-28T15:35:34","date_gmt":"2022-10-28T13:35:34","guid":{"rendered":"http:\/\/www.crfj.org\/?p=15958"},"modified":"2022-11-11T08:05:11","modified_gmt":"2022-11-11T07:05:11","slug":"archeologie-ouverture-de-la-fouille-de-shaar-hagolan-juin-2022","status":"publish","type":"post","link":"https:\/\/www.crfj.org\/en\/archeologie-ouverture-de-la-fouille-de-shaar-hagolan-juin-2022\/","title":{"rendered":"ARCH\u00c9OLOGIE : ouverture de la fouille de Sha\u2019ar Hagolan (juin 2022)."},"content":{"rendered":"<p>Ouverture d&rsquo;une fouille programm\u00e9e sur le site embl\u00e9matique de Sha\u2019ar Hagolan (vall\u00e9e du Jourdain, Isra\u00ebl) par une \u00e9quipe internationale co-dirig\u00e9e par Julien Vieugu\u00e9 (CRFJ) et Anna Eirikh-Rose (IAA). Cette fouille franco-isra\u00e9lienne vise \u00e0 mieux comprendre l\u2019\u00e9mergence des premi\u00e8res soci\u00e9t\u00e9s poti\u00e8res au Levant Sud, par la mise au jour des niveaux de transition PPN-PN de ce site cl\u00e9 du 7e\u00a0mill\u00e9naire. La premi\u00e8re campagne s\u2019est d\u00e9roul\u00e9e du 12 au 26 juin 2022. Elle a permis la d\u00e9couverte de deux ensembles architecturaux exceptionnellement bien pr\u00e9serv\u00e9s, dont un ayant livr\u00e9 une figurine compl\u00e8te, adoss\u00e9e \u00e0 l\u2019un des murs de la construction.\u00a0<br><\/p>\n\n\n\n<p>\u2022 Article sur la fouille de Sha&rsquo;ar Hagolan paru dans le&nbsp;<em>Jerusalem Post<\/em>&nbsp;le 7 juillet 2022 :&nbsp;<a href=\"https:\/\/www.jpost.com\/archaeology\/article-711462\" class=\"\">https:\/\/www.jpost.com\/archaeology\/article-711462<\/a>&nbsp;<\/p>\n\n\n\n<p>\u2022 Plus&nbsp;d\u2019information sur ce projet en vid\u00e9o :&nbsp;<a href=\"https:\/\/www.youtube.com\/channel\/UC9r6oNAAw-PTI5qNkDgBlMQ\" class=\"\">https:\/\/www.youtube.com\/channel\/UC9r6oNAAw-PTI5qNkDgBlMQ<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Ouverture d&rsquo;une fouille programm\u00e9e sur le site embl\u00e9matique de Sha\u2019ar Hagolan (vall\u00e9e du Jourdain, Isra\u00ebl) par une \u00e9quipe internationale co-dirig\u00e9e par Julien Vieugu\u00e9 (CRFJ) et Anna Eirikh-Rose (IAA). Cette fouille franco-isra\u00e9lienne vise \u00e0 mieux comprendre l\u2019\u00e9mergence des premi\u00e8res soci\u00e9t\u00e9s poti\u00e8res au Levant Sud, par la mise au jour des niveaux de transition PPN-PN de ce site [&hellip;]<\/p>","protected":false},"author":2,"featured_media":15969,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/posts\/15958"}],"collection":[{"href":"https:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/comments?post=15958"}],"version-history":[{"count":4,"href":"https:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/posts\/15958\/revisions"}],"predecessor-version":[{"id":15986,"href":"https:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/posts\/15958\/revisions\/15986"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/media\/15969"}],"wp:attachment":[{"href":"https:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/media?parent=15958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/categories?post=15958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/tags?post=15958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}