{"id":15948,"date":"2022-07-07T13:51:29","date_gmt":"2022-07-07T11:51:29","guid":{"rendered":"http:\/\/www.crfj.org\/wp-content\/uploads\/2022\/07\/Re\u0300glement-des-conseils-scientifiques-et-strate\u0301giques-des-UMIFRE.pdf"},"modified":"2022-07-07T13:51:29","modified_gmt":"2022-07-07T11:51:29","slug":"reglement-des-conseils-scientifiques-et-strategiques-des-umifre","status":"inherit","type":"attachment","link":"http:\/\/www.crfj.org\/en\/reglement-des-conseils-scientifiques-et-strategiques-des-umifre\/","title":{"rendered":"Re\u0300glement des conseils scientifiques et strate\u0301giques des UMIFRE"},"author":2,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a data-rel=\"iLightbox[postimages]\" data-title=\"Re\u0300glement des conseils scientifiques et strate\u0301giques des UMIFRE\" data-caption=\"\" href='https:\/\/www.crfj.org\/wp-content\/uploads\/2022\/07\/Re\u0300glement-des-conseils-scientifiques-et-strate\u0301giques-des-UMIFRE.pdf'><img width=\"212\" height=\"300\" src=\"https:\/\/www.crfj.org\/wp-content\/uploads\/2022\/07\/Re\u0300glement-des-conseils-scientifiques-et-strate\u0301giques-des-UMIFRE-pdf-212x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"file","mime_type":"application\/pdf","media_details":{"sizes":{"full":{"file":"Re\u0300glement-des-conseils-scientifiques-et-strate\u0301giques-des-UMIFRE-pdf.jpg","width":1058,"height":1497,"mime_type":"application\/pdf","source_url":"https:\/\/www.crfj.org\/wp-content\/uploads\/2022\/07\/Re\u0300glement-des-conseils-scientifiques-et-strate\u0301giques-des-UMIFRE-pdf.jpg"},"medium":{"file":"Re\u0300glement-des-conseils-scientifiques-et-strate\u0301giques-des-UMIFRE-pdf-212x300.jpg","width":212,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.crfj.org\/wp-content\/uploads\/2022\/07\/Re\u0300glement-des-conseils-scientifiques-et-strate\u0301giques-des-UMIFRE-pdf-212x300.jpg"},"large":{"file":"Re\u0300glement-des-conseils-scientifiques-et-strate\u0301giques-des-UMIFRE-pdf-724x1024.jpg","width":724,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/www.crfj.org\/wp-content\/uploads\/2022\/07\/Re\u0300glement-des-conseils-scientifiques-et-strate\u0301giques-des-UMIFRE-pdf-724x1024.jpg"},"thumbnail":{"file":"Re\u0300glement-des-conseils-scientifiques-et-strate\u0301giques-des-UMIFRE-pdf-106x150.jpg","width":106,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.crfj.org\/wp-content\/uploads\/2022\/07\/Re\u0300glement-des-conseils-scientifiques-et-strate\u0301giques-des-UMIFRE-pdf-106x150.jpg"}}},"post":null,"source_url":"https:\/\/www.crfj.org\/wp-content\/uploads\/2022\/07\/Re\u0300glement-des-conseils-scientifiques-et-strate\u0301giques-des-UMIFRE.pdf","_links":{"self":[{"href":"http:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/media\/15948"}],"collection":[{"href":"http:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.crfj.org\/en\/wp-json\/wp\/v2\/comments?post=15948"}]}}